{"id":4943,"date":"2026-03-12T15:35:02","date_gmt":"2026-03-12T15:35:02","guid":{"rendered":"https:\/\/home.hamptonu.edu\/research\/?page_id=4943"},"modified":"2026-03-12T15:38:09","modified_gmt":"2026-03-12T15:38:09","slug":"ibc-minutes","status":"publish","type":"page","link":"https:\/\/home.hamptonu.edu\/research\/ibc-minutes\/","title":{"rendered":"IBC Minutes"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4943\" class=\"elementor elementor-4943\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86d4226 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86d4226\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-48447f9\" data-id=\"48447f9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff2d0be elementor-widget elementor-widget-heading\" data-id=\"ff2d0be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">IBC Meeting Minutes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-71a23df elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"71a23df\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d785823\" data-id=\"d785823\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f165d88 elementor-widget elementor-widget-text-editor\" data-id=\"f165d88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/home.hamptonu.edu\/research\/wp-content\/uploads\/sites\/57\/2026\/03\/Meeting-Minutes_IBC-May16_2025.pdf\">May 16, 2025<\/a><br \/><a href=\"https:\/\/home.hamptonu.edu\/research\/wp-content\/uploads\/sites\/57\/2026\/03\/Meeting_Minutes_IBC_Oct7_2025.pdf\">October 7, 2025<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>IBC Meeting Minutes May 16, 2025October 7, 2025<\/p>\n","protected":false},"author":205,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-4943","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IBC Minutes - Hampton University Research<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/home.hamptonu.edu\/research\/ibc-minutes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IBC Minutes - Hampton University Research\" \/>\n<meta property=\"og:description\" content=\"IBC Meeting Minutes May 16, 2025October 7, 2025\" \/>\n<meta property=\"og:url\" content=\"https:\/\/home.hamptonu.edu\/research\/ibc-minutes\/\" \/>\n<meta property=\"og:site_name\" content=\"Hampton University Research\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-12T15:38:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/home.hamptonu.edu\\\/research\\\/ibc-minutes\\\/\",\"url\":\"https:\\\/\\\/home.hamptonu.edu\\\/research\\\/ibc-minutes\\\/\",\"name\":\"IBC Minutes - Hampton University Research\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/home.hamptonu.edu\\\/research\\\/#website\"},\"datePublished\":\"2026-03-12T15:35:02+00:00\",\"dateModified\":\"2026-03-12T15:38:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/home.hamptonu.edu\\\/research\\\/ibc-minutes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/home.hamptonu.edu\\\/research\\\/ibc-minutes\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/home.hamptonu.edu\\\/research\\\/ibc-minutes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/home.hamptonu.edu\\\/research\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IBC Minutes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/home.hamptonu.edu\\\/research\\\/#website\",\"url\":\"https:\\\/\\\/home.hamptonu.edu\\\/research\\\/\",\"name\":\"Hampton University Research\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/home.hamptonu.edu\\\/research\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/home.hamptonu.edu\\\/research\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/home.hamptonu.edu\\\/research\\\/#organization\",\"name\":\"Hampton University Research\",\"url\":\"https:\\\/\\\/home.hamptonu.edu\\\/research\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/home.hamptonu.edu\\\/research\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/home.hamptonu.edu\\\/research\\\/wp-content\\\/uploads\\\/sites\\\/57\\\/2024\\\/03\\\/logo-motto.png\",\"contentUrl\":\"https:\\\/\\\/home.hamptonu.edu\\\/research\\\/wp-content\\\/uploads\\\/sites\\\/57\\\/2024\\\/03\\\/logo-motto.png\",\"width\":250,\"height\":79,\"caption\":\"Hampton University Research\"},\"image\":{\"@id\":\"https:\\\/\\\/home.hamptonu.edu\\\/research\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IBC Minutes - Hampton University Research","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/home.hamptonu.edu\/research\/ibc-minutes\/","og_locale":"en_US","og_type":"article","og_title":"IBC Minutes - Hampton University Research","og_description":"IBC Meeting Minutes May 16, 2025October 7, 2025","og_url":"https:\/\/home.hamptonu.edu\/research\/ibc-minutes\/","og_site_name":"Hampton University Research","article_modified_time":"2026-03-12T15:38:09+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/home.hamptonu.edu\/research\/ibc-minutes\/","url":"https:\/\/home.hamptonu.edu\/research\/ibc-minutes\/","name":"IBC Minutes - Hampton University Research","isPartOf":{"@id":"https:\/\/home.hamptonu.edu\/research\/#website"},"datePublished":"2026-03-12T15:35:02+00:00","dateModified":"2026-03-12T15:38:09+00:00","breadcrumb":{"@id":"https:\/\/home.hamptonu.edu\/research\/ibc-minutes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/home.hamptonu.edu\/research\/ibc-minutes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/home.hamptonu.edu\/research\/ibc-minutes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/home.hamptonu.edu\/research\/"},{"@type":"ListItem","position":2,"name":"IBC Minutes"}]},{"@type":"WebSite","@id":"https:\/\/home.hamptonu.edu\/research\/#website","url":"https:\/\/home.hamptonu.edu\/research\/","name":"Hampton University Research","description":"","publisher":{"@id":"https:\/\/home.hamptonu.edu\/research\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/home.hamptonu.edu\/research\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/home.hamptonu.edu\/research\/#organization","name":"Hampton University Research","url":"https:\/\/home.hamptonu.edu\/research\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/home.hamptonu.edu\/research\/#\/schema\/logo\/image\/","url":"https:\/\/home.hamptonu.edu\/research\/wp-content\/uploads\/sites\/57\/2024\/03\/logo-motto.png","contentUrl":"https:\/\/home.hamptonu.edu\/research\/wp-content\/uploads\/sites\/57\/2024\/03\/logo-motto.png","width":250,"height":79,"caption":"Hampton University Research"},"image":{"@id":"https:\/\/home.hamptonu.edu\/research\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/home.hamptonu.edu\/research\/wp-json\/wp\/v2\/pages\/4943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/home.hamptonu.edu\/research\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/home.hamptonu.edu\/research\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/home.hamptonu.edu\/research\/wp-json\/wp\/v2\/users\/205"}],"replies":[{"embeddable":true,"href":"https:\/\/home.hamptonu.edu\/research\/wp-json\/wp\/v2\/comments?post=4943"}],"version-history":[{"count":4,"href":"https:\/\/home.hamptonu.edu\/research\/wp-json\/wp\/v2\/pages\/4943\/revisions"}],"predecessor-version":[{"id":4951,"href":"https:\/\/home.hamptonu.edu\/research\/wp-json\/wp\/v2\/pages\/4943\/revisions\/4951"}],"wp:attachment":[{"href":"https:\/\/home.hamptonu.edu\/research\/wp-json\/wp\/v2\/media?parent=4943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}